
{"id":9344,"date":"2016-08-11T15:38:07","date_gmt":"2016-08-11T13:38:07","guid":{"rendered":"https:\/\/www.brickrknowledge.de\/fr\/?page_id=9344"},"modified":"2016-12-22T11:37:26","modified_gmt":"2016-12-22T10:37:26","slug":"basic-set","status":"publish","type":"page","link":"https:\/\/www.brickrknowledge.eu\/fr\/sets\/experiments\/basic-set\/","title":{"rendered":"Basic Set"},"content":{"rendered":"\n\t\n\t<div class=\"container\" style=\"margin-top: 43px; margin-bottom: 43px;\">\n\t\t<div class=\"row\">\n\n\t\t\t\t\t\t\t<div class=\"col-sm-2 col-xs-6\">\n\t\t\t\t\t<img decoding=\"async\" class=\"img-responsive\" src=\"\" \/>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"col-sm-2 col-xs-6\">\n\t\t\t\t\t<img decoding=\"async\" class=\"img-responsive\" src=\"\" \/>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"col-sm-2 col-xs-6\">\n\t\t\t\t\t<img decoding=\"async\" class=\"img-responsive\" src=\"\" \/>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"col-sm-2 col-xs-6\">\n\t\t\t\t\t<img decoding=\"async\" class=\"img-responsive\" src=\"\" \/>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"col-sm-2 col-xs-6\">\n\t\t\t\t\t<img decoding=\"async\" class=\"img-responsive\" src=\"\" \/>\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t\t<div class=\"col-sm-2 col-xs-6\">\n\t\t\t\t\t\t<div class=\"youtube_image\" style=\"position: relative;\">\n\n\t\t\t\t\t\t\t<a class=\"fancybox-media\" href=\"https:\/\/www.youtube.com\/watch?v=d5kgmXPEEDM\">\n\t\t\t\t\t\t\t\t<i style=\"position:absolute;\n\t\t\t\t\t\t\t\t\t  left: 0;\n\t\t\t\t\t\t\t\t\t  right: 0;\n\t\t\t\t\t\t\t\t\t  margin: 0 auto;\n\t\t\t\t\t\t\t\t\t  text-align: center;\n\t\t\t\t\t\t\t\t\t  z-index: 100;\n\t\t\t\t\t\t\t\t\t  color: #fff;\n\t\t\t\t\t\t\t\t\t  top: 25%\n\t\t\t\t\t\t\t\t\t  \" class=\"fa fa-youtube-play fa-4x\"><\/i>\n\n\t\t\t\t\t\t\t<div style=\"background: #444; opacity: 0.3; height: 100%; width: 100%; position: absolute; z-index: 99;\"><\/div>\n\t\t\t\t\t\t\t<img decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/www.brickrknowledge.de\/content\/uploads\/2015\/04\/basic-set-yt.png\" alt=\"\"\/>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\n\n\t\t<\/div>\n\t<\/div>\n\n\n\t\n<p>Une exp\u00e9rience amusante pour toute la famille : le set basic de Brick \u00b4R \u00b4knowledge comprend 19 Bricks de fonctions diff\u00e9rentes.<br \/>\nAvec ce set vous et vos enfants devienent menbres officiels de la g\u00e9n\u00e9ration Maker.<br \/>\nId\u00e9al pour les d\u00e9butants mais aussi exigeants dans la r\u00e9alisation des circuits.<\/p>\n\n\t\n\n\t<div class=\"download_container category_container clearfix\" style=\"width: 400px; margin-top: 48px; margin-bottom: 48px; float: left; margin-right: 24px; min-height: 340px !important;\">\n\n\t\t<div class=\"download_thumb\" style=\"float:left; width: 50px;\">\n\t\t\t<a href=\"\/content\/uploads\/2015\/04\/BRK_Basic_handbuch_screen.pdf\" target=\"_blank\" style=\"text-transform: uppercase;\"><i class=\"fa fa-file-pdf-o fa-4x\"><\/i><\/a>\n\t\t<\/div>\n\n\t\t<div class=\"download_content\" style=\"float: left; margin-left: 30px; width: 280px;\">\n\t\t\t<h3 style=\"margin-top: 0;\">Basic Set Handbuch Deutsch<\/h3>\n\t\t\t<p>Das Handbuch zum Basic Set enth\u00e4lt die Erkl\u00e4rung der darin enthaltenen Bricks. Du findest darin auch einige Beispielschaltungen, die du nachbauen oder als Inspiration f\u00fcr neue Ideen verwenden kannst.<\/p>\n\n\n\t\t\t<a href=\"\/content\/uploads\/2015\/04\/BRK_Basic_handbuch_screen.pdf\" target=\"_blank\" style=\"text-transform: uppercase;\">>> Download now<\/a>\n\t\t<\/div>\n\t<\/div>\n\n\n\n\t\n\n\t\n\t<div class=\"download_container category_container clearfix\" style=\"width: 400px; margin-top: 48px; margin-bottom: 48px; float: left; margin-right: 24px; min-height: 340px !important;\">\n\n\t\t<div class=\"download_thumb\" style=\"float:left; width: 50px;\">\n\t\t\t<a href=\"115589.html\" target=\"_blank\"><i class=\"fa fa-cart-plus fa-4x\"><\/i><\/a>\n\t\t<\/div>\n\n\t\t<div class=\"download_content\" style=\"float: left; margin-left: 30px; width: 280px;\">\n\t\t\t<h3 style=\"margin-top: 0;\">Basic Set - Dans la boutique<\/h3>\n\t\t\t<p>\n\t\t\t\t\t\t\t<\/p>\n\n\t\t\t<p>\n\t\t\t\t<strong>Art.-ID:<\/strong> 115589<br \/>\n\t\t\t\t<strong>Manufacturer-ID:<\/strong> ALL-BRICK-0374<br \/>\n\t\t\t\t<strong>EAN-Code:<\/strong>  4038816115584<br \/><br \/><br \/>\n\t\t\t<\/p>\n\n\t\t\t<a href=\"https:\/\/shop.maker-store.de\/ArtByOrdernumber\/forward\/article\/115589\" target=\"_blank\">>> Order now<\/a>\n\t\t<\/div>\n\t<\/div>\n\n\n\t\n\n\t<div class=\"container\" style=\"margin-top: 43px; clear: both;\">\n\t\t<div class=\"row\">\n\n\t\t\t\n\n\n\n\n\n\t    <div class=\"container\" style=\"padding-bottom: 64px;\">\n        <div class=\"row\">\n\n\t\t\t\n\t\t\t\t\n                <div class=\"col-lg-2 col-md-4 col-xs-6\" style=\"margin-bottom: 16px;\">\n                    <div class=\"flip-container\" ontouchstart=\"this.classList.toggle('hover');\" style=\"text-align: center;\">\n                        <div class=\"flipper\">\n                            <div class=\"front\">\n\n                                <div class=\"productImg\" style=\"width: 70px; margin: 0 auto;\">\n\n                                    <img decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/www.brickrknowledge.eu\/content\/uploads\/2015\/04\/Pic_ALL-BRICK-0001-150x150.jpg\" alt=\"\"\/>\n\n\n                                <\/div> <!--\/ .productImg -->\n\n                                <div class=\"productText\" style=\"margin-top: 16px;\">\n                                    <span class=\"amount\">\n\t\t\t\t\t\t\t\t\t\t1x\t\t\t\t\t\t\t\t\t<\/span>\n\n                                    <h4 style=\"margin-top: 0; font-size: 14px;\">\n\t\t\t\t\t\t\t\t\t\tBatterie Adapter                                    <\/h4>\n                                <\/div> <!--\/ .productText -->\n                            <\/div> <!--\/ .front -->\n\n                            <div class=\"back\">\n\n                                <div class=\"productImg\" style=\"width: 70px; margin: 0 auto 16px auto;\">\n\t\t\t\t\t\t\t\t\t                                        <img decoding=\"async\" class=\"img-responsive\" src=\"\" alt=\" - Art.-ID: 113628\" style=\"margin: 0 auto;\" \/>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t                                <\/div>\n\n                                <div class=\"productText\" style=\"\">\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t                                            <a href=\"https:\/\/shop.maker-store.de\/ArtByOrdernumber\/forward\/article\/113628\" target=\"_blank\">\n                                                <i class=\"icon ion-ios-cart-outline\" style=\"font-size: 28px;\"><\/i>\n                                            <\/a>\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\n                                    <a href=\"#inline\" id=\"10058\" class=\"icon ion-ios-search brick_more\" style=\"font-size: 28px;\"><\/a>\n                                    <!--<a href=\"#scheme\" id=\"scheme_10058\" class=\"icon ion-wrench brick_scheme\" style=\"font-size: 24px;\"><\/a>-->\n                                <\/div> <!--\/ .productText -->\n                            <\/div> <!--\/ .back -->\n                        <\/div> <!--\/ .flipper -->\n\n                    <\/div> <!--\/ .flip-container -->\n                <\/div> <!--\/ .col-sm-2 -->\n\n\t\t\t\n\t\t\t\t\n                <div class=\"col-lg-2 col-md-4 col-xs-6\" style=\"margin-bottom: 16px;\">\n                    <div class=\"flip-container\" ontouchstart=\"this.classList.toggle('hover');\" style=\"text-align: center;\">\n                        <div class=\"flipper\">\n                            <div class=\"front\">\n\n                                <div class=\"productImg\" style=\"width: 70px; margin: 0 auto;\">\n\n                                    <img decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/www.brickrknowledge.eu\/content\/uploads\/2015\/04\/Pic_ALL-BRICK-0042-150x150.jpg\" alt=\"\"\/>\n\n\n                                <\/div> <!--\/ .productImg -->\n\n                                <div class=\"productText\" style=\"margin-top: 16px;\">\n                                    <span class=\"amount\">\n\t\t\t\t\t\t\t\t\t\t1x\t\t\t\t\t\t\t\t\t<\/span>\n\n                                    <h4 style=\"margin-top: 0; font-size: 14px;\">\n\t\t\t\t\t\t\t\t\t\tKondensator 100\u00b5F elko 25V                                    <\/h4>\n                                <\/div> <!--\/ .productText -->\n                            <\/div> <!--\/ .front -->\n\n                            <div class=\"back\">\n\n                                <div class=\"productImg\" style=\"width: 70px; margin: 0 auto 16px auto;\">\n\t\t\t\t\t\t\t\t\t                                        <img decoding=\"async\" class=\"img-responsive\" src=\"\" alt=\" - Art.-ID: 113669\" style=\"margin: 0 auto;\" \/>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t                                <\/div>\n\n                                <div class=\"productText\" style=\"\">\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t                                            <a href=\"https:\/\/shop.maker-store.de\/ArtByOrdernumber\/forward\/article\/113669\" target=\"_blank\">\n                                                <i class=\"icon ion-ios-cart-outline\" style=\"font-size: 28px;\"><\/i>\n                                            <\/a>\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\n                                    <a href=\"#inline\" id=\"10003\" class=\"icon ion-ios-search brick_more\" style=\"font-size: 28px;\"><\/a>\n                                    <!--<a href=\"#scheme\" id=\"scheme_10003\" class=\"icon ion-wrench brick_scheme\" style=\"font-size: 24px;\"><\/a>-->\n                                <\/div> <!--\/ .productText -->\n                            <\/div> <!--\/ .back -->\n                        <\/div> <!--\/ .flipper -->\n\n                    <\/div> <!--\/ .flip-container -->\n                <\/div> <!--\/ .col-sm-2 -->\n\n\t\t\t\n\t\t\t\t\n                <div class=\"col-lg-2 col-md-4 col-xs-6\" style=\"margin-bottom: 16px;\">\n                    <div class=\"flip-container\" ontouchstart=\"this.classList.toggle('hover');\" style=\"text-align: center;\">\n                        <div class=\"flipper\">\n                            <div class=\"front\">\n\n                                <div class=\"productImg\" style=\"width: 70px; margin: 0 auto;\">\n\n                                    <img decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/www.brickrknowledge.eu\/content\/uploads\/2015\/04\/Pic_ALL-BRICK-0040-150x150.jpg\" alt=\"\"\/>\n\n\n                                <\/div> <!--\/ .productImg -->\n\n                                <div class=\"productText\" style=\"margin-top: 16px;\">\n                                    <span class=\"amount\">\n\t\t\t\t\t\t\t\t\t\t1x\t\t\t\t\t\t\t\t\t<\/span>\n\n                                    <h4 style=\"margin-top: 0; font-size: 14px;\">\n\t\t\t\t\t\t\t\t\t\tKondensator 10\u00b5F 25V                                    <\/h4>\n                                <\/div> <!--\/ .productText -->\n                            <\/div> <!--\/ .front -->\n\n                            <div class=\"back\">\n\n                                <div class=\"productImg\" style=\"width: 70px; margin: 0 auto 16px auto;\">\n\t\t\t\t\t\t\t\t\t                                        <img decoding=\"async\" class=\"img-responsive\" src=\"\" alt=\" - Art.-ID: 113667\" style=\"margin: 0 auto;\" \/>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t                                <\/div>\n\n                                <div class=\"productText\" style=\"\">\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t                                            <a href=\"https:\/\/shop.maker-store.de\/ArtByOrdernumber\/forward\/article\/113667\" target=\"_blank\">\n                                                <i class=\"icon ion-ios-cart-outline\" style=\"font-size: 28px;\"><\/i>\n                                            <\/a>\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\n                                    <a href=\"#inline\" id=\"10007\" class=\"icon ion-ios-search brick_more\" style=\"font-size: 28px;\"><\/a>\n                                    <!--<a href=\"#scheme\" id=\"scheme_10007\" class=\"icon ion-wrench brick_scheme\" style=\"font-size: 24px;\"><\/a>-->\n                                <\/div> <!--\/ .productText -->\n                            <\/div> <!--\/ .back -->\n                        <\/div> <!--\/ .flipper -->\n\n                    <\/div> <!--\/ .flip-container -->\n                <\/div> <!--\/ .col-sm-2 -->\n\n\t\t\t\n\t\t\t\t\n                <div class=\"col-lg-2 col-md-4 col-xs-6\" style=\"margin-bottom: 16px;\">\n                    <div class=\"flip-container\" ontouchstart=\"this.classList.toggle('hover');\" style=\"text-align: center;\">\n                        <div class=\"flipper\">\n                            <div class=\"front\">\n\n                                <div class=\"productImg\" style=\"width: 70px; margin: 0 auto;\">\n\n                                    <img decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/www.brickrknowledge.eu\/content\/uploads\/2015\/04\/Pic_ALL-BRICK-0012-150x150.jpg\" alt=\"\"\/>\n\n\n                                <\/div> <!--\/ .productImg -->\n\n                                <div class=\"productText\" style=\"margin-top: 16px;\">\n                                    <span class=\"amount\">\n\t\t\t\t\t\t\t\t\t\t1x\t\t\t\t\t\t\t\t\t<\/span>\n\n                                    <h4 style=\"margin-top: 0; font-size: 14px;\">\n\t\t\t\t\t\t\t\t\t\tLED green                                    <\/h4>\n                                <\/div> <!--\/ .productText -->\n                            <\/div> <!--\/ .front -->\n\n                            <div class=\"back\">\n\n                                <div class=\"productImg\" style=\"width: 70px; margin: 0 auto 16px auto;\">\n\t\t\t\t\t\t\t\t\t                                        <img decoding=\"async\" class=\"img-responsive\" src=\"\" alt=\" - Art.-ID: 113639\" style=\"margin: 0 auto;\" \/>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t                                <\/div>\n\n                                <div class=\"productText\" style=\"\">\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t                                            <a href=\"https:\/\/shop.maker-store.de\/ArtByOrdernumber\/forward\/article\/113639\" target=\"_blank\">\n                                                <i class=\"icon ion-ios-cart-outline\" style=\"font-size: 28px;\"><\/i>\n                                            <\/a>\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\n                                    <a href=\"#inline\" id=\"10037\" class=\"icon ion-ios-search brick_more\" style=\"font-size: 28px;\"><\/a>\n                                    <!--<a href=\"#scheme\" id=\"scheme_10037\" class=\"icon ion-wrench brick_scheme\" style=\"font-size: 24px;\"><\/a>-->\n                                <\/div> <!--\/ .productText -->\n                            <\/div> <!--\/ .back -->\n                        <\/div> <!--\/ .flipper -->\n\n                    <\/div> <!--\/ .flip-container -->\n                <\/div> <!--\/ .col-sm-2 -->\n\n\t\t\t\n\t\t\t\t\n                <div class=\"col-lg-2 col-md-4 col-xs-6\" style=\"margin-bottom: 16px;\">\n                    <div class=\"flip-container\" ontouchstart=\"this.classList.toggle('hover');\" style=\"text-align: center;\">\n                        <div class=\"flipper\">\n                            <div class=\"front\">\n\n                                <div class=\"productImg\" style=\"width: 70px; margin: 0 auto;\">\n\n                                    <img decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/www.brickrknowledge.eu\/content\/uploads\/2015\/04\/Pic_ALL-BRICK-0011-150x150.jpg\" alt=\"\"\/>\n\n\n                                <\/div> <!--\/ .productImg -->\n\n                                <div class=\"productText\" style=\"margin-top: 16px;\">\n                                    <span class=\"amount\">\n\t\t\t\t\t\t\t\t\t\t1x\t\t\t\t\t\t\t\t\t<\/span>\n\n                                    <h4 style=\"margin-top: 0; font-size: 14px;\">\n\t\t\t\t\t\t\t\t\t\tLED yellow                                    <\/h4>\n                                <\/div> <!--\/ .productText -->\n                            <\/div> <!--\/ .front -->\n\n                            <div class=\"back\">\n\n                                <div class=\"productImg\" style=\"width: 70px; margin: 0 auto 16px auto;\">\n\t\t\t\t\t\t\t\t\t                                        <img decoding=\"async\" class=\"img-responsive\" src=\"\" alt=\" - Art.-ID: 113638\" style=\"margin: 0 auto;\" \/>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t                                <\/div>\n\n                                <div class=\"productText\" style=\"\">\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t                                            <a href=\"https:\/\/shop.maker-store.de\/ArtByOrdernumber\/forward\/article\/113638\" target=\"_blank\">\n                                                <i class=\"icon ion-ios-cart-outline\" style=\"font-size: 28px;\"><\/i>\n                                            <\/a>\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\n                                    <a href=\"#inline\" id=\"10039\" class=\"icon ion-ios-search brick_more\" style=\"font-size: 28px;\"><\/a>\n                                    <!--<a href=\"#scheme\" id=\"scheme_10039\" class=\"icon ion-wrench brick_scheme\" style=\"font-size: 24px;\"><\/a>-->\n                                <\/div> <!--\/ .productText -->\n                            <\/div> <!--\/ .back -->\n                        <\/div> <!--\/ .flipper -->\n\n                    <\/div> <!--\/ .flip-container -->\n                <\/div> <!--\/ .col-sm-2 -->\n\n\t\t\t\n\t\t\t\t\n                <div class=\"col-lg-2 col-md-4 col-xs-6\" style=\"margin-bottom: 16px;\">\n                    <div class=\"flip-container\" ontouchstart=\"this.classList.toggle('hover');\" style=\"text-align: center;\">\n                        <div class=\"flipper\">\n                            <div class=\"front\">\n\n                                <div class=\"productImg\" style=\"width: 70px; margin: 0 auto;\">\n\n                                    <img decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/www.brickrknowledge.eu\/content\/uploads\/2015\/04\/dl_basic-set_handbuch-150x150.jpg\" alt=\"\"\/>\n\n\n                                <\/div> <!--\/ .productImg -->\n\n                                <div class=\"productText\" style=\"margin-top: 16px;\">\n                                    <span class=\"amount\">\n\t\t\t\t\t\t\t\t\t\t1x\t\t\t\t\t\t\t\t\t<\/span>\n\n                                    <h4 style=\"margin-top: 0; font-size: 14px;\">\n\t\t\t\t\t\t\t\t\t\tManual Basic Set                                    <\/h4>\n                                <\/div> <!--\/ .productText -->\n                            <\/div> <!--\/ .front -->\n\n                            <div class=\"back\">\n\n                                <div class=\"productImg\" style=\"width: 70px; margin: 0 auto 16px auto;\">\n\t\t\t\t\t\t\t\t\t                                        <img decoding=\"async\" class=\"img-responsive\" src=\"\" alt=\" - Art.-ID: 116008\" style=\"margin: 0 auto;\" \/>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t                                <\/div>\n\n                                <div class=\"productText\" style=\"\">\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t                                            <a href=\"https:\/\/shop.maker-store.de\/ArtByOrdernumber\/forward\/article\/116008\" target=\"_blank\">\n                                                <i class=\"icon ion-ios-cart-outline\" style=\"font-size: 28px;\"><\/i>\n                                            <\/a>\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\n                                    <a href=\"#inline\" id=\"9941\" class=\"icon ion-ios-search brick_more\" style=\"font-size: 28px;\"><\/a>\n                                    <!--<a href=\"#scheme\" id=\"scheme_9941\" class=\"icon ion-wrench brick_scheme\" style=\"font-size: 24px;\"><\/a>-->\n                                <\/div> <!--\/ .productText -->\n                            <\/div> <!--\/ .back -->\n                        <\/div> <!--\/ .flipper -->\n\n                    <\/div> <!--\/ .flip-container -->\n                <\/div> <!--\/ .col-sm-2 -->\n\n\t\t\t\n\t\t\t\t\n                <div class=\"col-lg-2 col-md-4 col-xs-6\" style=\"margin-bottom: 16px;\">\n                    <div class=\"flip-container\" ontouchstart=\"this.classList.toggle('hover');\" style=\"text-align: center;\">\n                        <div class=\"flipper\">\n                            <div class=\"front\">\n\n                                <div class=\"productImg\" style=\"width: 70px; margin: 0 auto;\">\n\n                                    <img decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/www.brickrknowledge.eu\/content\/uploads\/2015\/04\/Pic_ALL-BRICK-0027-150x150.jpg\" alt=\"\"\/>\n\n\n                                <\/div> <!--\/ .productImg -->\n\n                                <div class=\"productText\" style=\"margin-top: 16px;\">\n                                    <span class=\"amount\">\n\t\t\t\t\t\t\t\t\t\t1x\t\t\t\t\t\t\t\t\t<\/span>\n\n                                    <h4 style=\"margin-top: 0; font-size: 14px;\">\n\t\t\t\t\t\t\t\t\t\tPotentiometer 10kOhm                                    <\/h4>\n                                <\/div> <!--\/ .productText -->\n                            <\/div> <!--\/ .front -->\n\n                            <div class=\"back\">\n\n                                <div class=\"productImg\" style=\"width: 70px; margin: 0 auto 16px auto;\">\n\t\t\t\t\t\t\t\t\t                                        <img decoding=\"async\" class=\"img-responsive\" src=\"\" alt=\" - Art.-ID: 113654\" style=\"margin: 0 auto;\" \/>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t                                <\/div>\n\n                                <div class=\"productText\" style=\"\">\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t                                            <a href=\"https:\/\/shop.maker-store.de\/ArtByOrdernumber\/forward\/article\/113654\" target=\"_blank\">\n                                                <i class=\"icon ion-ios-cart-outline\" style=\"font-size: 28px;\"><\/i>\n                                            <\/a>\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\n                                    <a href=\"#inline\" id=\"10015\" class=\"icon ion-ios-search brick_more\" style=\"font-size: 28px;\"><\/a>\n                                    <!--<a href=\"#scheme\" id=\"scheme_10015\" class=\"icon ion-wrench brick_scheme\" style=\"font-size: 24px;\"><\/a>-->\n                                <\/div> <!--\/ .productText -->\n                            <\/div> <!--\/ .back -->\n                        <\/div> <!--\/ .flipper -->\n\n                    <\/div> <!--\/ .flip-container -->\n                <\/div> <!--\/ .col-sm-2 -->\n\n\t\t\t\n\t\t\t\t\n                <div class=\"col-lg-2 col-md-4 col-xs-6\" style=\"margin-bottom: 16px;\">\n                    <div class=\"flip-container\" ontouchstart=\"this.classList.toggle('hover');\" style=\"text-align: center;\">\n                        <div class=\"flipper\">\n                            <div class=\"front\">\n\n                                <div class=\"productImg\" style=\"width: 70px; margin: 0 auto;\">\n\n                                    <img decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/www.brickrknowledge.eu\/content\/uploads\/2015\/04\/Pic_ALL-BRICK-0028-150x150.jpg\" alt=\"\"\/>\n\n\n                                <\/div> <!--\/ .productImg -->\n\n                                <div class=\"productText\" style=\"margin-top: 16px;\">\n                                    <span class=\"amount\">\n\t\t\t\t\t\t\t\t\t\t1x\t\t\t\t\t\t\t\t\t<\/span>\n\n                                    <h4 style=\"margin-top: 0; font-size: 14px;\">\n\t\t\t\t\t\t\t\t\t\tResistance Photo resistor LDR 03                                    <\/h4>\n                                <\/div> <!--\/ .productText -->\n                            <\/div> <!--\/ .front -->\n\n                            <div class=\"back\">\n\n                                <div class=\"productImg\" style=\"width: 70px; margin: 0 auto 16px auto;\">\n\t\t\t\t\t\t\t\t\t                                        <img decoding=\"async\" class=\"img-responsive\" src=\"\" alt=\" - Art.-ID: 113655\" style=\"margin: 0 auto;\" \/>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t                                <\/div>\n\n                                <div class=\"productText\" style=\"\">\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t                                            <a href=\"https:\/\/shop.maker-store.de\/ArtByOrdernumber\/forward\/article\/113655\" target=\"_blank\">\n                                                <i class=\"icon ion-ios-cart-outline\" style=\"font-size: 28px;\"><\/i>\n                                            <\/a>\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\n                                    <a href=\"#inline\" id=\"10013\" class=\"icon ion-ios-search brick_more\" style=\"font-size: 28px;\"><\/a>\n                                    <!--<a href=\"#scheme\" id=\"scheme_10013\" class=\"icon ion-wrench brick_scheme\" style=\"font-size: 24px;\"><\/a>-->\n                                <\/div> <!--\/ .productText -->\n                            <\/div> <!--\/ .back -->\n                        <\/div> <!--\/ .flipper -->\n\n                    <\/div> <!--\/ .flip-container -->\n                <\/div> <!--\/ .col-sm-2 -->\n\n\t\t\t\n\t\t\t\t\n                <div class=\"col-lg-2 col-md-4 col-xs-6\" style=\"margin-bottom: 16px;\">\n                    <div class=\"flip-container\" ontouchstart=\"this.classList.toggle('hover');\" style=\"text-align: center;\">\n                        <div class=\"flipper\">\n                            <div class=\"front\">\n\n                                <div class=\"productImg\" style=\"width: 70px; margin: 0 auto;\">\n\n                                    <img decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/www.brickrknowledge.eu\/content\/uploads\/2015\/04\/Pic_ALL-BRICK-0022-150x150.jpg\" alt=\"\"\/>\n\n\n                                <\/div> <!--\/ .productImg -->\n\n                                <div class=\"productText\" style=\"margin-top: 16px;\">\n                                    <span class=\"amount\">\n\t\t\t\t\t\t\t\t\t\t1x\t\t\t\t\t\t\t\t\t<\/span>\n\n                                    <h4 style=\"margin-top: 0; font-size: 14px;\">\n\t\t\t\t\t\t\t\t\t\tResistor 100kOhm                                    <\/h4>\n                                <\/div> <!--\/ .productText -->\n                            <\/div> <!--\/ .front -->\n\n                            <div class=\"back\">\n\n                                <div class=\"productImg\" style=\"width: 70px; margin: 0 auto 16px auto;\">\n\t\t\t\t\t\t\t\t\t                                        <img decoding=\"async\" class=\"img-responsive\" src=\"\" alt=\" - Art.-ID: 113649\" style=\"margin: 0 auto;\" \/>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t                                <\/div>\n\n                                <div class=\"productText\" style=\"\">\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t                                            <a href=\"https:\/\/shop.maker-store.de\/ArtByOrdernumber\/forward\/article\/113649\" target=\"_blank\">\n                                                <i class=\"icon ion-ios-cart-outline\" style=\"font-size: 28px;\"><\/i>\n                                            <\/a>\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\n                                    <a href=\"#inline\" id=\"10023\" class=\"icon ion-ios-search brick_more\" style=\"font-size: 28px;\"><\/a>\n                                    <!--<a href=\"#scheme\" id=\"scheme_10023\" class=\"icon ion-wrench brick_scheme\" style=\"font-size: 24px;\"><\/a>-->\n                                <\/div> <!--\/ .productText -->\n                            <\/div> <!--\/ .back -->\n                        <\/div> <!--\/ .flipper -->\n\n                    <\/div> <!--\/ .flip-container -->\n                <\/div> <!--\/ .col-sm-2 -->\n\n\t\t\t\n\t\t\t\t\n                <div class=\"col-lg-2 col-md-4 col-xs-6\" style=\"margin-bottom: 16px;\">\n                    <div class=\"flip-container\" ontouchstart=\"this.classList.toggle('hover');\" style=\"text-align: center;\">\n                        <div class=\"flipper\">\n                            <div class=\"front\">\n\n                                <div class=\"productImg\" style=\"width: 70px; margin: 0 auto;\">\n\n                                    <img decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/www.brickrknowledge.eu\/content\/uploads\/2015\/04\/Pic_ALL-BRICK-0021-150x150.jpg\" alt=\"\"\/>\n\n\n                                <\/div> <!--\/ .productImg -->\n\n                                <div class=\"productText\" style=\"margin-top: 16px;\">\n                                    <span class=\"amount\">\n\t\t\t\t\t\t\t\t\t\t1x\t\t\t\t\t\t\t\t\t<\/span>\n\n                                    <h4 style=\"margin-top: 0; font-size: 14px;\">\n\t\t\t\t\t\t\t\t\t\tResistor 10kOhm                                    <\/h4>\n                                <\/div> <!--\/ .productText -->\n                            <\/div> <!--\/ .front -->\n\n                            <div class=\"back\">\n\n                                <div class=\"productImg\" style=\"width: 70px; margin: 0 auto 16px auto;\">\n\t\t\t\t\t\t\t\t\t                                        <img decoding=\"async\" class=\"img-responsive\" src=\"\" alt=\" - Art.-ID: 113648\" style=\"margin: 0 auto;\" \/>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t                                <\/div>\n\n                                <div class=\"productText\" style=\"\">\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t                                            <a href=\"https:\/\/shop.maker-store.de\/ArtByOrdernumber\/forward\/article\/113648\" target=\"_blank\">\n                                                <i class=\"icon ion-ios-cart-outline\" style=\"font-size: 28px;\"><\/i>\n                                            <\/a>\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\n                                    <a href=\"#inline\" id=\"10025\" class=\"icon ion-ios-search brick_more\" style=\"font-size: 28px;\"><\/a>\n                                    <!--<a href=\"#scheme\" id=\"scheme_10025\" class=\"icon ion-wrench brick_scheme\" style=\"font-size: 24px;\"><\/a>-->\n                                <\/div> <!--\/ .productText -->\n                            <\/div> <!--\/ .back -->\n                        <\/div> <!--\/ .flipper -->\n\n                    <\/div> <!--\/ .flip-container -->\n                <\/div> <!--\/ .col-sm-2 -->\n\n\t\t\t\n\t\t\t\t\n                <div class=\"col-lg-2 col-md-4 col-xs-6\" style=\"margin-bottom: 16px;\">\n                    <div class=\"flip-container\" ontouchstart=\"this.classList.toggle('hover');\" style=\"text-align: center;\">\n                        <div class=\"flipper\">\n                            <div class=\"front\">\n\n                                <div class=\"productImg\" style=\"width: 70px; margin: 0 auto;\">\n\n                                    <img decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/www.brickrknowledge.eu\/content\/uploads\/2015\/04\/Pic_ALL-BRICK-0030-150x150.jpg\" alt=\"\"\/>\n\n\n                                <\/div> <!--\/ .productImg -->\n\n                                <div class=\"productText\" style=\"margin-top: 16px;\">\n                                    <span class=\"amount\">\n\t\t\t\t\t\t\t\t\t\t1x\t\t\t\t\t\t\t\t\t<\/span>\n\n                                    <h4 style=\"margin-top: 0; font-size: 14px;\">\n\t\t\t\t\t\t\t\t\t\tTransistor npn BC817                                    <\/h4>\n                                <\/div> <!--\/ .productText -->\n                            <\/div> <!--\/ .front -->\n\n                            <div class=\"back\">\n\n                                <div class=\"productImg\" style=\"width: 70px; margin: 0 auto 16px auto;\">\n\t\t\t\t\t\t\t\t\t                                        <img decoding=\"async\" class=\"img-responsive\" src=\"\" alt=\" - Art.-ID: 113657\" style=\"margin: 0 auto;\" \/>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t                                <\/div>\n\n                                <div class=\"productText\" style=\"\">\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t                                            <a href=\"https:\/\/shop.maker-store.de\/ArtByOrdernumber\/forward\/article\/113657\" target=\"_blank\">\n                                                <i class=\"icon ion-ios-cart-outline\" style=\"font-size: 28px;\"><\/i>\n                                            <\/a>\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\n                                    <a href=\"#inline\" id=\"10011\" class=\"icon ion-ios-search brick_more\" style=\"font-size: 28px;\"><\/a>\n                                    <!--<a href=\"#scheme\" id=\"scheme_10011\" class=\"icon ion-wrench brick_scheme\" style=\"font-size: 24px;\"><\/a>-->\n                                <\/div> <!--\/ .productText -->\n                            <\/div> <!--\/ .back -->\n                        <\/div> <!--\/ .flipper -->\n\n                    <\/div> <!--\/ .flip-container -->\n                <\/div> <!--\/ .col-sm-2 -->\n\n\t\t\t\n\t\t\t\t\n                <div class=\"col-lg-2 col-md-4 col-xs-6\" style=\"margin-bottom: 16px;\">\n                    <div class=\"flip-container\" ontouchstart=\"this.classList.toggle('hover');\" style=\"text-align: center;\">\n                        <div class=\"flipper\">\n                            <div class=\"front\">\n\n                                <div class=\"productImg\" style=\"width: 70px; margin: 0 auto;\">\n\n                                    <img decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/www.brickrknowledge.eu\/content\/uploads\/2015\/04\/Pic_ALL-BRICK-01451-150x150.jpg\" alt=\"\"\/>\n\n\n                                <\/div> <!--\/ .productImg -->\n\n                                <div class=\"productText\" style=\"margin-top: 16px;\">\n                                    <span class=\"amount\">\n\t\t\t\t\t\t\t\t\t\t1x\t\t\t\t\t\t\t\t\t<\/span>\n\n                                    <h4 style=\"margin-top: 0; font-size: 14px;\">\n\t\t\t\t\t\t\t\t\t\tUniversalsockel                                    <\/h4>\n                                <\/div> <!--\/ .productText -->\n                            <\/div> <!--\/ .front -->\n\n                            <div class=\"back\">\n\n                                <div class=\"productImg\" style=\"width: 70px; margin: 0 auto 16px auto;\">\n\t\t\t\t\t\t\t\t\t                                        <img decoding=\"async\" class=\"img-responsive\" src=\"\" alt=\" - Art.-ID: 116009\" style=\"margin: 0 auto;\" \/>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t                                <\/div>\n\n                                <div class=\"productText\" style=\"\">\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t                                            <a href=\"https:\/\/shop.maker-store.de\/ArtByOrdernumber\/forward\/article\/116009\" target=\"_blank\">\n                                                <i class=\"icon ion-ios-cart-outline\" style=\"font-size: 28px;\"><\/i>\n                                            <\/a>\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\n                                    <a href=\"#inline\" id=\"9937\" class=\"icon ion-ios-search brick_more\" style=\"font-size: 28px;\"><\/a>\n                                    <!--<a href=\"#scheme\" id=\"scheme_9937\" class=\"icon ion-wrench brick_scheme\" style=\"font-size: 24px;\"><\/a>-->\n                                <\/div> <!--\/ .productText -->\n                            <\/div> <!--\/ .back -->\n                        <\/div> <!--\/ .flipper -->\n\n                    <\/div> <!--\/ .flip-container -->\n                <\/div> <!--\/ .col-sm-2 -->\n\n\t\t\t\n\t\t\t\t\n                <div class=\"col-lg-2 col-md-4 col-xs-6\" style=\"margin-bottom: 16px;\">\n                    <div class=\"flip-container\" ontouchstart=\"this.classList.toggle('hover');\" style=\"text-align: center;\">\n                        <div class=\"flipper\">\n                            <div class=\"front\">\n\n                                <div class=\"productImg\" style=\"width: 70px; margin: 0 auto;\">\n\n                                    <img decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/www.brickrknowledge.eu\/content\/uploads\/2015\/04\/Pic_ALL-BRICK-0005-150x150.jpg\" alt=\"\"\/>\n\n\n                                <\/div> <!--\/ .productImg -->\n\n                                <div class=\"productText\" style=\"margin-top: 16px;\">\n                                    <span class=\"amount\">\n\t\t\t\t\t\t\t\t\t\t2x\t\t\t\t\t\t\t\t\t<\/span>\n\n                                    <h4 style=\"margin-top: 0; font-size: 14px;\">\n\t\t\t\t\t\t\t\t\t\tWire corner                                    <\/h4>\n                                <\/div> <!--\/ .productText -->\n                            <\/div> <!--\/ .front -->\n\n                            <div class=\"back\">\n\n                                <div class=\"productImg\" style=\"width: 70px; margin: 0 auto 16px auto;\">\n\t\t\t\t\t\t\t\t\t                                        <img decoding=\"async\" class=\"img-responsive\" src=\"\" alt=\" - Art.-ID: 113632\" style=\"margin: 0 auto;\" \/>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t                                <\/div>\n\n                                <div class=\"productText\" style=\"\">\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t                                            <a href=\"https:\/\/shop.maker-store.de\/ArtByOrdernumber\/forward\/article\/113632\" target=\"_blank\">\n                                                <i class=\"icon ion-ios-cart-outline\" style=\"font-size: 28px;\"><\/i>\n                                            <\/a>\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\n                                    <a href=\"#inline\" id=\"10051\" class=\"icon ion-ios-search brick_more\" style=\"font-size: 28px;\"><\/a>\n                                    <!--<a href=\"#scheme\" id=\"scheme_10051\" class=\"icon ion-wrench brick_scheme\" style=\"font-size: 24px;\"><\/a>-->\n                                <\/div> <!--\/ .productText -->\n                            <\/div> <!--\/ .back -->\n                        <\/div> <!--\/ .flipper -->\n\n                    <\/div> <!--\/ .flip-container -->\n                <\/div> <!--\/ .col-sm-2 -->\n\n\t\t\t\n\t\t\t\t\n                <div class=\"col-lg-2 col-md-4 col-xs-6\" style=\"margin-bottom: 16px;\">\n                    <div class=\"flip-container\" ontouchstart=\"this.classList.toggle('hover');\" style=\"text-align: center;\">\n                        <div class=\"flipper\">\n                            <div class=\"front\">\n\n                                <div class=\"productImg\" style=\"width: 70px; margin: 0 auto;\">\n\n                                    <img decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/www.brickrknowledge.eu\/content\/uploads\/2015\/04\/Pic_ALL-BRICK-0003-150x150.jpg\" alt=\"\"\/>\n\n\n                                <\/div> <!--\/ .productImg -->\n\n                                <div class=\"productText\" style=\"margin-top: 16px;\">\n                                    <span class=\"amount\">\n\t\t\t\t\t\t\t\t\t\t3x\t\t\t\t\t\t\t\t\t<\/span>\n\n                                    <h4 style=\"margin-top: 0; font-size: 14px;\">\n\t\t\t\t\t\t\t\t\t\tWire ground                                    <\/h4>\n                                <\/div> <!--\/ .productText -->\n                            <\/div> <!--\/ .front -->\n\n                            <div class=\"back\">\n\n                                <div class=\"productImg\" style=\"width: 70px; margin: 0 auto 16px auto;\">\n\t\t\t\t\t\t\t\t\t                                        <img decoding=\"async\" class=\"img-responsive\" src=\"\" alt=\" - Art.-ID: 113630\" style=\"margin: 0 auto;\" \/>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t                                <\/div>\n\n                                <div class=\"productText\" style=\"\">\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t                                            <a href=\"https:\/\/shop.maker-store.de\/ArtByOrdernumber\/forward\/article\/113630\" target=\"_blank\">\n                                                <i class=\"icon ion-ios-cart-outline\" style=\"font-size: 28px;\"><\/i>\n                                            <\/a>\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\n                                    <a href=\"#inline\" id=\"10054\" class=\"icon ion-ios-search brick_more\" style=\"font-size: 28px;\"><\/a>\n                                    <!--<a href=\"#scheme\" id=\"scheme_10054\" class=\"icon ion-wrench brick_scheme\" style=\"font-size: 24px;\"><\/a>-->\n                                <\/div> <!--\/ .productText -->\n                            <\/div> <!--\/ .back -->\n                        <\/div> <!--\/ .flipper -->\n\n                    <\/div> <!--\/ .flip-container -->\n                <\/div> <!--\/ .col-sm-2 -->\n\n\t\t\t\n\t\t\t\t\n                <div class=\"col-lg-2 col-md-4 col-xs-6\" style=\"margin-bottom: 16px;\">\n                    <div class=\"flip-container\" ontouchstart=\"this.classList.toggle('hover');\" style=\"text-align: center;\">\n                        <div class=\"flipper\">\n                            <div class=\"front\">\n\n                                <div class=\"productImg\" style=\"width: 70px; margin: 0 auto;\">\n\n                                    <img decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/www.brickrknowledge.eu\/content\/uploads\/2015\/04\/Pic_ALL-BRICK-0006-150x150.jpg\" alt=\"\"\/>\n\n\n                                <\/div> <!--\/ .productImg -->\n\n                                <div class=\"productText\" style=\"margin-top: 16px;\">\n                                    <span class=\"amount\">\n\t\t\t\t\t\t\t\t\t\t3x\t\t\t\t\t\t\t\t\t<\/span>\n\n                                    <h4 style=\"margin-top: 0; font-size: 14px;\">\n\t\t\t\t\t\t\t\t\t\tWire T-crossing                                    <\/h4>\n                                <\/div> <!--\/ .productText -->\n                            <\/div> <!--\/ .front -->\n\n                            <div class=\"back\">\n\n                                <div class=\"productImg\" style=\"width: 70px; margin: 0 auto 16px auto;\">\n\t\t\t\t\t\t\t\t\t                                        <img decoding=\"async\" class=\"img-responsive\" src=\"\" alt=\" - Art.-ID: 113633\" style=\"margin: 0 auto;\" \/>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t                                <\/div>\n\n                                <div class=\"productText\" style=\"\">\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t                                            <a href=\"https:\/\/shop.maker-store.de\/ArtByOrdernumber\/forward\/article\/113633\" target=\"_blank\">\n                                                <i class=\"icon ion-ios-cart-outline\" style=\"font-size: 28px;\"><\/i>\n                                            <\/a>\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\n                                    <a href=\"#inline\" id=\"10049\" class=\"icon ion-ios-search brick_more\" style=\"font-size: 28px;\"><\/a>\n                                    <!--<a href=\"#scheme\" id=\"scheme_10049\" class=\"icon ion-wrench brick_scheme\" style=\"font-size: 24px;\"><\/a>-->\n                                <\/div> <!--\/ .productText -->\n                            <\/div> <!--\/ .back -->\n                        <\/div> <!--\/ .flipper -->\n\n                    <\/div> <!--\/ .flip-container -->\n                <\/div> <!--\/ .col-sm-2 -->\n\n\t\t\t\t\t\t        <\/div> <!--\/ .row -->\n    <\/div> <!--\/ flipper -->\n    <\/div>\n\n\n\n\n\t\t\t\n\n\t\t<\/div>\n\t<\/div>\n\n\t\n","protected":false},"excerpt":{"rendered":"<p>Une exp\u00e9rience amusante pour toute la famille : le set basic de Brick \u00b4R \u00b4knowledge comprend 19 Bricks de fonctions diff\u00e9rentes. Avec ce set vous et vos enfants devienent menbres officiels de la g\u00e9n\u00e9ration Maker. Id\u00e9al pour les d\u00e9butants mais aussi exigeants dans la r\u00e9alisation des circuits.<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":10080,"menu_order":0,"comment_status":"open","ping_status":"closed","template":"page_sets.php","meta":{"footnotes":""},"categories":[],"tags":[],"class_list":["post-9344","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Basic Set - Brick&#039;R&#039;knowledge<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/brickrknowledge.eu\/fr\/sets\/experiments\/basic-set\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Basic Set - Brick&#039;R&#039;knowledge\" \/>\n<meta property=\"og:description\" content=\"Une exp\u00e9rience amusante pour toute la famille : le set basic de Brick \u00b4R \u00b4knowledge comprend 19 Bricks de fonctions diff\u00e9rentes. Avec ce set vous et vos enfants devienent menbres officiels de la g\u00e9n\u00e9ration Maker. Id\u00e9al pour les d\u00e9butants mais aussi exigeants dans la r\u00e9alisation des circuits.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/brickrknowledge.eu\/fr\/sets\/experiments\/basic-set\/\" \/>\n<meta property=\"og:site_name\" content=\"Brick&#039;R&#039;knowledge\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/BrickRknowledge\" \/>\n<meta property=\"article:modified_time\" content=\"2016-12-22T10:37:26+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@brickrknowledge\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/brickrknowledge.eu\/fr\/sets\/experiments\/basic-set\/\",\"url\":\"https:\/\/brickrknowledge.eu\/fr\/sets\/experiments\/basic-set\/\",\"name\":\"Basic Set - Brick&#039;R&#039;knowledge\",\"isPartOf\":{\"@id\":\"https:\/\/www.brickrknowledge.com\/en\/#website\"},\"datePublished\":\"2016-08-11T13:38:07+00:00\",\"dateModified\":\"2016-12-22T10:37:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/brickrknowledge.eu\/fr\/sets\/experiments\/basic-set\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/brickrknowledge.eu\/fr\/sets\/experiments\/basic-set\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/brickrknowledge.eu\/fr\/sets\/experiments\/basic-set\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/brickrknowledge.eu\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sets\",\"item\":\"https:\/\/brickrknowledge.eu\/fr\/sets\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Experiments\",\"item\":\"https:\/\/brickrknowledge.eu\/fr\/sets\/experiments\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Basic Set\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.brickrknowledge.com\/en\/#website\",\"url\":\"https:\/\/www.brickrknowledge.com\/en\/\",\"name\":\"Brick&#039;R&#039;knowledge\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.brickrknowledge.com\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Basic Set - Brick&#039;R&#039;knowledge","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/brickrknowledge.eu\/fr\/sets\/experiments\/basic-set\/","og_locale":"fr_FR","og_type":"article","og_title":"Basic Set - Brick&#039;R&#039;knowledge","og_description":"Une exp\u00e9rience amusante pour toute la famille : le set basic de Brick \u00b4R \u00b4knowledge comprend 19 Bricks de fonctions diff\u00e9rentes. Avec ce set vous et vos enfants devienent menbres officiels de la g\u00e9n\u00e9ration Maker. Id\u00e9al pour les d\u00e9butants mais aussi exigeants dans la r\u00e9alisation des circuits.","og_url":"https:\/\/brickrknowledge.eu\/fr\/sets\/experiments\/basic-set\/","og_site_name":"Brick&#039;R&#039;knowledge","article_publisher":"https:\/\/www.facebook.com\/BrickRknowledge","article_modified_time":"2016-12-22T10:37:26+00:00","twitter_card":"summary_large_image","twitter_site":"@brickrknowledge","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/brickrknowledge.eu\/fr\/sets\/experiments\/basic-set\/","url":"https:\/\/brickrknowledge.eu\/fr\/sets\/experiments\/basic-set\/","name":"Basic Set - Brick&#039;R&#039;knowledge","isPartOf":{"@id":"https:\/\/www.brickrknowledge.com\/en\/#website"},"datePublished":"2016-08-11T13:38:07+00:00","dateModified":"2016-12-22T10:37:26+00:00","breadcrumb":{"@id":"https:\/\/brickrknowledge.eu\/fr\/sets\/experiments\/basic-set\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/brickrknowledge.eu\/fr\/sets\/experiments\/basic-set\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/brickrknowledge.eu\/fr\/sets\/experiments\/basic-set\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/brickrknowledge.eu\/fr\/"},{"@type":"ListItem","position":2,"name":"Sets","item":"https:\/\/brickrknowledge.eu\/fr\/sets\/"},{"@type":"ListItem","position":3,"name":"Experiments","item":"https:\/\/brickrknowledge.eu\/fr\/sets\/experiments\/"},{"@type":"ListItem","position":4,"name":"Basic Set"}]},{"@type":"WebSite","@id":"https:\/\/www.brickrknowledge.com\/en\/#website","url":"https:\/\/www.brickrknowledge.com\/en\/","name":"Brick&#039;R&#039;knowledge","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.brickrknowledge.com\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/www.brickrknowledge.eu\/fr\/wp-json\/wp\/v2\/pages\/9344"}],"collection":[{"href":"https:\/\/www.brickrknowledge.eu\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.brickrknowledge.eu\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.brickrknowledge.eu\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brickrknowledge.eu\/fr\/wp-json\/wp\/v2\/comments?post=9344"}],"version-history":[{"count":0,"href":"https:\/\/www.brickrknowledge.eu\/fr\/wp-json\/wp\/v2\/pages\/9344\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/www.brickrknowledge.eu\/fr\/wp-json\/wp\/v2\/pages\/10080"}],"wp:attachment":[{"href":"https:\/\/www.brickrknowledge.eu\/fr\/wp-json\/wp\/v2\/media?parent=9344"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brickrknowledge.eu\/fr\/wp-json\/wp\/v2\/categories?post=9344"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brickrknowledge.eu\/fr\/wp-json\/wp\/v2\/tags?post=9344"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}