
{"id":9256,"date":"2016-08-03T12:37:46","date_gmt":"2016-08-03T10:37:46","guid":{"rendered":"https:\/\/www.brickrknowledge.de\/it\/?p=9256"},"modified":"2016-08-03T12:37:46","modified_gmt":"2016-08-03T10:37:46","slug":"lelettronica-puo-essere-divertente","status":"publish","type":"post","link":"https:\/\/www.brickrknowledge.eu\/it\/lelettronica-puo-essere-divertente\/","title":{"rendered":"L\u2019elettronica pu\u00f2 essere divertente!?"},"content":{"rendered":"<p>Hai ancora dubbi? Perch\u00e9 non partecipi a uno dei nostri laboratori in Agosto: ne faremo uno sulla robotica nel nostro <a href=\"https:\/\/www.maker-store.de\/en\/\">Maker Store a Berlino<\/a> l\u20198 Agosto.<\/p>\n<p><a href=\"https:\/\/www.brickrknowledge.de\/content\/uploads\/2016\/07\/M_Bot.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-9135\" src=\"https:\/\/www.brickrknowledge.de\/content\/uploads\/2016\/07\/M_Bot-300x225.jpg\" alt=\"M_Bot\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.brickrknowledge.eu\/content\/uploads\/2016\/07\/M_Bot-300x225.jpg 300w, https:\/\/www.brickrknowledge.eu\/content\/uploads\/2016\/07\/M_Bot-600x450.jpg 600w, https:\/\/www.brickrknowledge.eu\/content\/uploads\/2016\/07\/M_Bot-427x320.jpg 427w, https:\/\/www.brickrknowledge.eu\/content\/uploads\/2016\/07\/M_Bot-440x330.jpg 440w, https:\/\/www.brickrknowledge.eu\/content\/uploads\/2016\/07\/M_Bot.jpg 640w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Hai sempre voluto costruire e programmare il tuo robot personale? Se si questo laboratorio fa proprio al caso tuo: per prima cosa assemblerai un \u201c<a href=\"http:\/\/learn.makeblock.com\/mbot\/\">mBot<\/a>\u201d. Quindi assisterai ad un introduzione nel mondo della programmazione Arduino basata su Scratch e avrai la possibilit\u00e0 di insegnare al tuo robot qualsiasi tipo di cosa, tutto \u00e8 possibile.<\/p>\n<p><a href=\"https:\/\/www.brickrknowledge.de\/content\/uploads\/2016\/07\/Elektronik_Fortg_900x900p.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-9139\" src=\"https:\/\/www.brickrknowledge.de\/content\/uploads\/2016\/07\/Elektronik_Fortg_900x900p-300x300.jpg\" alt=\"Elektronik_Fortg_900x900p\" width=\"300\" height=\"300\" srcset=\"https:\/\/www.brickrknowledge.eu\/content\/uploads\/2016\/07\/Elektronik_Fortg_900x900p-300x300.jpg 300w, https:\/\/www.brickrknowledge.eu\/content\/uploads\/2016\/07\/Elektronik_Fortg_900x900p-150x150.jpg 150w, https:\/\/www.brickrknowledge.eu\/content\/uploads\/2016\/07\/Elektronik_Fortg_900x900p-768x768.jpg 768w, https:\/\/www.brickrknowledge.eu\/content\/uploads\/2016\/07\/Elektronik_Fortg_900x900p-600x600.jpg 600w, https:\/\/www.brickrknowledge.eu\/content\/uploads\/2016\/07\/Elektronik_Fortg_900x900p-320x320.jpg 320w, https:\/\/www.brickrknowledge.eu\/content\/uploads\/2016\/07\/Elektronik_Fortg_900x900p-330x330.jpg 330w, https:\/\/www.brickrknowledge.eu\/content\/uploads\/2016\/07\/Elektronik_Fortg_900x900p.jpg 900w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Nel nostro laboratorio <a href=\"https:\/\/www.maker-store.de\/en\/product\/electronics-for-beginners\/\">\u201cElettronica per principianti\u201d<\/a> per persone dai 10 anni in su, ci piacerebbe introdurti le basi pi\u00f9 importanti dell\u2019elettronica. Imparerai cos\u2019\u00e8 un circuito elettronico, come una resistenza funziona in serie e in parallelo e cosa puoi fare con un transistor. Successivamente costruirai il tuo sistema di allarme che porterai a casa dopo il laboratorio.<br \/>\nNel laboratorio <a href=\"https:\/\/www.maker-store.de\/en\/product\/electronics-for-advanced\/\">\u201cElettronica avanzata\u201d<\/a> \u00e8 possibile approfondire la conoscenza per quanto riguarda l\u2019ingegneria elettronica: arriverai a conoscere condensatori elettrolitici, induttanze, rel\u00e8, transistor e transistor ad effetto di campo. In pi\u00f9, costruirai circuiti elettronici (con un timer NE555), circuiti logici, circuiti con oscillatori e\/o amplificatori.<\/p>\n<p><a href=\"https:\/\/www.brickrknowledge.de\/content\/uploads\/2016\/07\/Arduino_Stammtisch_900x900p.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-9143\" src=\"https:\/\/www.brickrknowledge.de\/content\/uploads\/2016\/07\/Arduino_Stammtisch_900x900p-300x300.jpg\" alt=\"Arduino_Stammtisch_900x900p\" width=\"300\" height=\"300\" srcset=\"https:\/\/www.brickrknowledge.eu\/content\/uploads\/2016\/07\/Arduino_Stammtisch_900x900p-300x300.jpg 300w, https:\/\/www.brickrknowledge.eu\/content\/uploads\/2016\/07\/Arduino_Stammtisch_900x900p-150x150.jpg 150w, https:\/\/www.brickrknowledge.eu\/content\/uploads\/2016\/07\/Arduino_Stammtisch_900x900p-768x768.jpg 768w, https:\/\/www.brickrknowledge.eu\/content\/uploads\/2016\/07\/Arduino_Stammtisch_900x900p-600x600.jpg 600w, https:\/\/www.brickrknowledge.eu\/content\/uploads\/2016\/07\/Arduino_Stammtisch_900x900p-320x320.jpg 320w, https:\/\/www.brickrknowledge.eu\/content\/uploads\/2016\/07\/Arduino_Stammtisch_900x900p-330x330.jpg 330w, https:\/\/www.brickrknowledge.eu\/content\/uploads\/2016\/07\/Arduino_Stammtisch_900x900p.jpg 900w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Nel nostro laboratorio <a href=\"https:\/\/www.maker-store.de\/en\/product\/coding-workshop-2\/\">\u201cArduino coding\u201d<\/a> ti introdurremo all\u2019elettronica digitale e alla codifica di microcontrollori e le relative basi su di essi. Faremo lampeggiare LEDs e tratteremo convertitori analogico\/digitali, bus I2C, rel\u00e8, chiavi, monitor di rotazione ed OLED.<\/p>\n<p><a href=\"https:\/\/www.brickrknowledge.de\/content\/uploads\/2016\/07\/L\u00f6ten_900x900p.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-9147\" src=\"https:\/\/www.brickrknowledge.de\/content\/uploads\/2016\/07\/L\u00f6ten_900x900p-300x300.jpg\" alt=\"L\u00f6ten_900x900p\" width=\"300\" height=\"300\" srcset=\"https:\/\/www.brickrknowledge.eu\/content\/uploads\/2016\/07\/L\u00f6ten_900x900p-300x300.jpg 300w, https:\/\/www.brickrknowledge.eu\/content\/uploads\/2016\/07\/L\u00f6ten_900x900p-150x150.jpg 150w, https:\/\/www.brickrknowledge.eu\/content\/uploads\/2016\/07\/L\u00f6ten_900x900p-768x768.jpg 768w, https:\/\/www.brickrknowledge.eu\/content\/uploads\/2016\/07\/L\u00f6ten_900x900p-600x600.jpg 600w, https:\/\/www.brickrknowledge.eu\/content\/uploads\/2016\/07\/L\u00f6ten_900x900p-320x320.jpg 320w, https:\/\/www.brickrknowledge.eu\/content\/uploads\/2016\/07\/L\u00f6ten_900x900p-330x330.jpg 330w, https:\/\/www.brickrknowledge.eu\/content\/uploads\/2016\/07\/L\u00f6ten_900x900p.jpg 900w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>In aggiunta, offriamo <a href=\"https:\/\/www.maker-store.de\/en\/product\/soldering-workshop\/\">un laboratorio di saldatura<\/a> per tutte le persone interessate all\u2019argomento. Per prima cosa, si arriva a conoscere le attrezzature di base, come lo stagnatore e saldatore e poi potrai iniziare la vera fase di lavoro: saldare la propria base di bricks e portarli a casa dopo il laboratorio.<\/p>\n<p><a href=\"https:\/\/www.maker-store.de\/en\/shop\/\">\u00a0Registrati ora \u2013 ci sono pochi posti ancora disponibili!<\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hai ancora dubbi? Perch\u00e9 non partecipi a uno dei nostri laboratori in Agosto: ne faremo uno sulla robotica nel nostro Maker Store a Berlino l\u20198 Agosto. Hai sempre voluto costruire e programmare il tuo robot personale? Se si questo laboratorio fa proprio al caso tuo: per prima cosa assemblerai un \u201cmBot\u201d. Quindi assisterai ad un [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":9162,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[93],"tags":[],"class_list":["post-9256","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorised-it"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>L\u2019elettronica pu\u00f2 essere divertente!? - Brick&#039;R&#039;knowledge<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.brickrknowledge.de\/it\/lelettronica-puo-essere-divertente\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L\u2019elettronica pu\u00f2 essere divertente!? - Brick&#039;R&#039;knowledge\" \/>\n<meta property=\"og:description\" content=\"Hai ancora dubbi? Perch\u00e9 non partecipi a uno dei nostri laboratori in Agosto: ne faremo uno sulla robotica nel nostro Maker Store a Berlino l\u20198 Agosto. Hai sempre voluto costruire e programmare il tuo robot personale? Se si questo laboratorio fa proprio al caso tuo: per prima cosa assemblerai un \u201cmBot\u201d. Quindi assisterai ad un [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.brickrknowledge.de\/it\/lelettronica-puo-essere-divertente\/\" \/>\n<meta property=\"og:site_name\" content=\"Brick&#039;R&#039;knowledge\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/BrickRknowledge\" \/>\n<meta property=\"article:published_time\" content=\"2016-08-03T10:37:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.brickrknowledge.de\/content\/uploads\/2016\/07\/L\u00f6ten-1024x680.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"680\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Lena Wahlsdorf\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@brickrknowledge\" \/>\n<meta name=\"twitter:site\" content=\"@brickrknowledge\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Lena Wahlsdorf\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.brickrknowledge.de\/it\/lelettronica-puo-essere-divertente\/\",\"url\":\"https:\/\/www.brickrknowledge.de\/it\/lelettronica-puo-essere-divertente\/\",\"name\":\"L\u2019elettronica pu\u00f2 essere divertente!? - Brick&#039;R&#039;knowledge\",\"isPartOf\":{\"@id\":\"https:\/\/www.brickrknowledge.com\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.brickrknowledge.de\/it\/lelettronica-puo-essere-divertente\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.brickrknowledge.de\/it\/lelettronica-puo-essere-divertente\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.brickrknowledge.eu\/content\/uploads\/2016\/07\/L\u00f6ten.jpg\",\"datePublished\":\"2016-08-03T10:37:46+00:00\",\"dateModified\":\"2016-08-03T10:37:46+00:00\",\"author\":{\"@id\":\"https:\/\/www.brickrknowledge.com\/en\/#\/schema\/person\/8f69a5236cc8657e68d506287d0ae975\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.brickrknowledge.de\/it\/lelettronica-puo-essere-divertente\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.brickrknowledge.de\/it\/lelettronica-puo-essere-divertente\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.brickrknowledge.de\/it\/lelettronica-puo-essere-divertente\/#primaryimage\",\"url\":\"https:\/\/www.brickrknowledge.eu\/content\/uploads\/2016\/07\/L\u00f6ten.jpg\",\"contentUrl\":\"https:\/\/www.brickrknowledge.eu\/content\/uploads\/2016\/07\/L\u00f6ten.jpg\",\"width\":4741,\"height\":3150},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.brickrknowledge.de\/it\/lelettronica-puo-essere-divertente\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/forum.brickrknowledge.eu\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L\u2019elettronica pu\u00f2 essere divertente!?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.brickrknowledge.com\/en\/#website\",\"url\":\"https:\/\/www.brickrknowledge.com\/en\/\",\"name\":\"Brick&#039;R&#039;knowledge\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.brickrknowledge.com\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.brickrknowledge.com\/en\/#\/schema\/person\/8f69a5236cc8657e68d506287d0ae975\",\"name\":\"Lena Wahlsdorf\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.brickrknowledge.com\/en\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0a15594e9d4b0fc995ab2548da24d794?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0a15594e9d4b0fc995ab2548da24d794?s=96&d=mm&r=g\",\"caption\":\"Lena Wahlsdorf\"},\"url\":\"https:\/\/www.brickrknowledge.eu\/it\/author\/lena\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L\u2019elettronica pu\u00f2 essere divertente!? - Brick&#039;R&#039;knowledge","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.brickrknowledge.de\/it\/lelettronica-puo-essere-divertente\/","og_locale":"it_IT","og_type":"article","og_title":"L\u2019elettronica pu\u00f2 essere divertente!? - Brick&#039;R&#039;knowledge","og_description":"Hai ancora dubbi? Perch\u00e9 non partecipi a uno dei nostri laboratori in Agosto: ne faremo uno sulla robotica nel nostro Maker Store a Berlino l\u20198 Agosto. Hai sempre voluto costruire e programmare il tuo robot personale? Se si questo laboratorio fa proprio al caso tuo: per prima cosa assemblerai un \u201cmBot\u201d. Quindi assisterai ad un [&hellip;]","og_url":"https:\/\/www.brickrknowledge.de\/it\/lelettronica-puo-essere-divertente\/","og_site_name":"Brick&#039;R&#039;knowledge","article_publisher":"https:\/\/www.facebook.com\/BrickRknowledge","article_published_time":"2016-08-03T10:37:46+00:00","og_image":[{"width":1024,"height":680,"url":"https:\/\/www.brickrknowledge.de\/content\/uploads\/2016\/07\/L\u00f6ten-1024x680.jpg","type":"image\/jpeg"}],"author":"Lena Wahlsdorf","twitter_card":"summary_large_image","twitter_creator":"@brickrknowledge","twitter_site":"@brickrknowledge","twitter_misc":{"Written by":"Lena Wahlsdorf","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.brickrknowledge.de\/it\/lelettronica-puo-essere-divertente\/","url":"https:\/\/www.brickrknowledge.de\/it\/lelettronica-puo-essere-divertente\/","name":"L\u2019elettronica pu\u00f2 essere divertente!? - Brick&#039;R&#039;knowledge","isPartOf":{"@id":"https:\/\/www.brickrknowledge.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.brickrknowledge.de\/it\/lelettronica-puo-essere-divertente\/#primaryimage"},"image":{"@id":"https:\/\/www.brickrknowledge.de\/it\/lelettronica-puo-essere-divertente\/#primaryimage"},"thumbnailUrl":"https:\/\/www.brickrknowledge.eu\/content\/uploads\/2016\/07\/L\u00f6ten.jpg","datePublished":"2016-08-03T10:37:46+00:00","dateModified":"2016-08-03T10:37:46+00:00","author":{"@id":"https:\/\/www.brickrknowledge.com\/en\/#\/schema\/person\/8f69a5236cc8657e68d506287d0ae975"},"breadcrumb":{"@id":"https:\/\/www.brickrknowledge.de\/it\/lelettronica-puo-essere-divertente\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.brickrknowledge.de\/it\/lelettronica-puo-essere-divertente\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.brickrknowledge.de\/it\/lelettronica-puo-essere-divertente\/#primaryimage","url":"https:\/\/www.brickrknowledge.eu\/content\/uploads\/2016\/07\/L\u00f6ten.jpg","contentUrl":"https:\/\/www.brickrknowledge.eu\/content\/uploads\/2016\/07\/L\u00f6ten.jpg","width":4741,"height":3150},{"@type":"BreadcrumbList","@id":"https:\/\/www.brickrknowledge.de\/it\/lelettronica-puo-essere-divertente\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/forum.brickrknowledge.eu\/it\/"},{"@type":"ListItem","position":2,"name":"L\u2019elettronica pu\u00f2 essere divertente!?"}]},{"@type":"WebSite","@id":"https:\/\/www.brickrknowledge.com\/en\/#website","url":"https:\/\/www.brickrknowledge.com\/en\/","name":"Brick&#039;R&#039;knowledge","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.brickrknowledge.com\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.brickrknowledge.com\/en\/#\/schema\/person\/8f69a5236cc8657e68d506287d0ae975","name":"Lena Wahlsdorf","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.brickrknowledge.com\/en\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/0a15594e9d4b0fc995ab2548da24d794?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0a15594e9d4b0fc995ab2548da24d794?s=96&d=mm&r=g","caption":"Lena Wahlsdorf"},"url":"https:\/\/www.brickrknowledge.eu\/it\/author\/lena\/"}]}},"_links":{"self":[{"href":"https:\/\/www.brickrknowledge.eu\/it\/wp-json\/wp\/v2\/posts\/9256"}],"collection":[{"href":"https:\/\/www.brickrknowledge.eu\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brickrknowledge.eu\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brickrknowledge.eu\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brickrknowledge.eu\/it\/wp-json\/wp\/v2\/comments?post=9256"}],"version-history":[{"count":0,"href":"https:\/\/www.brickrknowledge.eu\/it\/wp-json\/wp\/v2\/posts\/9256\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brickrknowledge.eu\/it\/wp-json\/wp\/v2\/media\/9162"}],"wp:attachment":[{"href":"https:\/\/www.brickrknowledge.eu\/it\/wp-json\/wp\/v2\/media?parent=9256"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brickrknowledge.eu\/it\/wp-json\/wp\/v2\/categories?post=9256"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brickrknowledge.eu\/it\/wp-json\/wp\/v2\/tags?post=9256"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}